{"id":1737,"date":"2009-09-15T08:02:43","date_gmt":"2009-09-15T16:02:43","guid":{"rendered":"http:\/\/joewelder.com\/?p=1737"},"modified":"2009-09-09T08:08:43","modified_gmt":"2009-09-09T16:08:43","slug":"welding-to-new-heights","status":"publish","type":"post","link":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/","title":{"rendered":"Welding to New Heights"},"content":{"rendered":"<p style=\"text-align: left;\">If you&#8217;re afraid of heights then this is not the job for you&#8230;  but check out this video clip of fabricators high atop a skyscraper&#8230;<object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"425\" height=\"344\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"https:\/\/www.youtube.com\/v\/8p4tUj0EOGg&amp;hl=en&amp;fs=1&amp;\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"425\" height=\"344\" src=\"https:\/\/www.youtube.com\/v\/8p4tUj0EOGg&amp;hl=en&amp;fs=1&amp;\" allowscriptaccess=\"always\" allowfullscreen=\"true\"><\/embed><\/object><\/p>\n<p>&#8230;and this video clip features <a href=\"http:\/\/www.mylincolnelectric.com\/Catalog\/equipmentseries.aspx?browse=102|706|&#038;locale=1033\">Lincoln Electric&#8217;s flux-cored welding technology<\/a>.  Pretty impressive stuff!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>If you&#8217;re afraid of heights then this is not the job for you&#8230; but check [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":8560,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[14,19,32],"tags":[],"class_list":["post-1737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-welding-history","category-just-for-kicks","category-welding-safety","entry","fw-tab-6 fw-tabr-4"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"If you&#039;re afraid of heights then this is not the job for you... but check out this video clip of fabricators high atop a skyscraper... ...and this video clip features Lincoln Electric&#039;s flux-cored welding technology. Pretty impressive stuff!\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Joe Welder\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Joe Welder\u2122 Blog -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Welding to New Heights - Joe Welder\u2122 Blog\" \/>\n\t\t<meta property=\"og:description\" content=\"If you&#039;re afraid of heights then this is not the job for you... but check out this video clip of fabricators high atop a skyscraper... ...and this video clip features Lincoln Electric&#039;s flux-cored welding technology. Pretty impressive stuff!\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2009-09-15T16:02:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2009-09-09T16:08:43+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Welding to New Heights - Joe Welder\u2122 Blog\" \/>\n\t\t<meta name=\"twitter:description\" content=\"If you&#039;re afraid of heights then this is not the job for you... but check out this video clip of fabricators high atop a skyscraper... ...and this video clip features Lincoln Electric&#039;s flux-cored welding technology. Pretty impressive stuff!\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/#blogposting\",\"name\":\"Welding to New Heights - Joe Welder\\u2122 Blog\",\"headline\":\"Welding to New Heights\",\"author\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/author\\\/editor\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/wp-content\\\/new_ups\\\/default-featured-image.png\",\"width\":300,\"height\":200,\"caption\":\"Default Featured Image\"},\"datePublished\":\"2009-09-15T08:02:43-07:00\",\"dateModified\":\"2009-09-09T08:08:43-07:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/#webpage\"},\"articleSection\":\"History, Welding Kicks, Welding Safety\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/category\\\/welding-industry-news\\\/#listItem\",\"name\":\"Welding Industry\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/category\\\/welding-industry-news\\\/#listItem\",\"position\":2,\"name\":\"Welding Industry\",\"item\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/category\\\/welding-industry-news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/category\\\/welding-industry-news\\\/welding-history\\\/#listItem\",\"name\":\"History\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/category\\\/welding-industry-news\\\/welding-history\\\/#listItem\",\"position\":3,\"name\":\"History\",\"item\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/category\\\/welding-industry-news\\\/welding-history\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/#listItem\",\"name\":\"Welding to New Heights\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/category\\\/welding-industry-news\\\/#listItem\",\"name\":\"Welding Industry\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/#listItem\",\"position\":4,\"name\":\"Welding to New Heights\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/category\\\/welding-industry-news\\\/welding-history\\\/#listItem\",\"name\":\"History\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/#organization\",\"name\":\"Joe Welder\\u2122 Blog\",\"url\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/wp-content\\\/new_ups\\\/Circle-A-Logo2021_PANTONE.png\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/#organizationLogo\",\"width\":1024,\"height\":977},\"image\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/author\\\/editor\\\/#author\",\"url\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/author\\\/editor\\\/\",\"name\":\"Joe Welder\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/#webpage\",\"url\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/\",\"name\":\"Welding to New Heights - Joe Welder\\u2122 Blog\",\"description\":\"If you're afraid of heights then this is not the job for you... but check out this video clip of fabricators high atop a skyscraper... ...and this video clip features Lincoln Electric's flux-cored welding technology. Pretty impressive stuff!\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/author\\\/editor\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/author\\\/editor\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/wp-content\\\/new_ups\\\/default-featured-image.png\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/#mainImage\",\"width\":300,\"height\":200,\"caption\":\"Default Featured Image\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/#mainImage\"},\"datePublished\":\"2009-09-15T08:02:43-07:00\",\"dateModified\":\"2009-09-09T08:08:43-07:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/#website\",\"url\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/\",\"name\":\"Joe Welder\\u2122 Blog\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Welding to New Heights - Joe Welder\u2122 Blog","description":"If you're afraid of heights then this is not the job for you... but check out this video clip of fabricators high atop a skyscraper... ...and this video clip features Lincoln Electric's flux-cored welding technology. Pretty impressive stuff!","canonical_url":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/#blogposting","name":"Welding to New Heights - Joe Welder\u2122 Blog","headline":"Welding to New Heights","author":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/author\/editor\/#author"},"publisher":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/blog.arc-zone.com\/joewelder\/wp-content\/new_ups\/default-featured-image.png","width":300,"height":200,"caption":"Default Featured Image"},"datePublished":"2009-09-15T08:02:43-07:00","dateModified":"2009-09-09T08:08:43-07:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/#webpage"},"isPartOf":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/#webpage"},"articleSection":"History, Welding Kicks, Welding Safety"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.arc-zone.com\/joewelder#listItem","position":1,"name":"Home","item":"https:\/\/blog.arc-zone.com\/joewelder","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.arc-zone.com\/joewelder\/category\/welding-industry-news\/#listItem","name":"Welding Industry"}},{"@type":"ListItem","@id":"https:\/\/blog.arc-zone.com\/joewelder\/category\/welding-industry-news\/#listItem","position":2,"name":"Welding Industry","item":"https:\/\/blog.arc-zone.com\/joewelder\/category\/welding-industry-news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.arc-zone.com\/joewelder\/category\/welding-industry-news\/welding-history\/#listItem","name":"History"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.arc-zone.com\/joewelder#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/blog.arc-zone.com\/joewelder\/category\/welding-industry-news\/welding-history\/#listItem","position":3,"name":"History","item":"https:\/\/blog.arc-zone.com\/joewelder\/category\/welding-industry-news\/welding-history\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/#listItem","name":"Welding to New Heights"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.arc-zone.com\/joewelder\/category\/welding-industry-news\/#listItem","name":"Welding Industry"}},{"@type":"ListItem","@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/#listItem","position":4,"name":"Welding to New Heights","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.arc-zone.com\/joewelder\/category\/welding-industry-news\/welding-history\/#listItem","name":"History"}}]},{"@type":"Organization","@id":"https:\/\/blog.arc-zone.com\/joewelder\/#organization","name":"Joe Welder\u2122 Blog","url":"https:\/\/blog.arc-zone.com\/joewelder\/","logo":{"@type":"ImageObject","url":"https:\/\/blog.arc-zone.com\/joewelder\/wp-content\/new_ups\/Circle-A-Logo2021_PANTONE.png","@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/#organizationLogo","width":1024,"height":977},"image":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/blog.arc-zone.com\/joewelder\/author\/editor\/#author","url":"https:\/\/blog.arc-zone.com\/joewelder\/author\/editor\/","name":"Joe Welder"},{"@type":"WebPage","@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/#webpage","url":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/","name":"Welding to New Heights - Joe Welder\u2122 Blog","description":"If you're afraid of heights then this is not the job for you... but check out this video clip of fabricators high atop a skyscraper... ...and this video clip features Lincoln Electric's flux-cored welding technology. Pretty impressive stuff!","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/#website"},"breadcrumb":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/#breadcrumblist"},"author":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/author\/editor\/#author"},"creator":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/author\/editor\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/blog.arc-zone.com\/joewelder\/wp-content\/new_ups\/default-featured-image.png","@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/#mainImage","width":300,"height":200,"caption":"Default Featured Image"},"primaryImageOfPage":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/#mainImage"},"datePublished":"2009-09-15T08:02:43-07:00","dateModified":"2009-09-09T08:08:43-07:00"},{"@type":"WebSite","@id":"https:\/\/blog.arc-zone.com\/joewelder\/#website","url":"https:\/\/blog.arc-zone.com\/joewelder\/","name":"Joe Welder\u2122 Blog","inLanguage":"en-US","publisher":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/#organization"}}]},"og:locale":"en_US","og:site_name":"Joe Welder\u2122 Blog -","og:type":"article","og:title":"Welding to New Heights - Joe Welder\u2122 Blog","og:description":"If you're afraid of heights then this is not the job for you... but check out this video clip of fabricators high atop a skyscraper... ...and this video clip features Lincoln Electric's flux-cored welding technology. Pretty impressive stuff!","og:url":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/","article:published_time":"2009-09-15T16:02:43+00:00","article:modified_time":"2009-09-09T16:08:43+00:00","twitter:card":"summary_large_image","twitter:title":"Welding to New Heights - Joe Welder\u2122 Blog","twitter:description":"If you're afraid of heights then this is not the job for you... but check out this video clip of fabricators high atop a skyscraper... ...and this video clip features Lincoln Electric's flux-cored welding technology. Pretty impressive stuff!"},"aioseo_meta_data":{"post_id":"1737","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-02-10 17:34:48","updated":"2025-06-04 10:46:40","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.arc-zone.com\/joewelder\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.arc-zone.com\/joewelder\/category\/welding-industry-news\/\" title=\"Welding Industry\">Welding Industry<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.arc-zone.com\/joewelder\/category\/welding-industry-news\/welding-history\/\" title=\"History\">History<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tWelding to New Heights\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/blog.arc-zone.com\/joewelder"},{"label":"Welding Industry","link":"https:\/\/blog.arc-zone.com\/joewelder\/category\/welding-industry-news\/"},{"label":"History","link":"https:\/\/blog.arc-zone.com\/joewelder\/category\/welding-industry-news\/welding-history\/"},{"label":"Welding to New Heights","link":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Welding to New Heights - Joe Welder\u2122 Blog<\/title>\n<meta name=\"description\" content=\"Welding to New Heights - Joe Welder\u2122 Blog -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joe Welder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/\"},\"author\":{\"name\":\"Joe Welder\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/#\\\/schema\\\/person\\\/d11eef7e30a3295231fc0ea473ff9505\"},\"headline\":\"Welding to New Heights\",\"datePublished\":\"2009-09-15T16:02:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/\"},\"wordCount\":44,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/wp-content\\\/new_ups\\\/default-featured-image.png\",\"articleSection\":[\"History\",\"Welding Kicks\",\"Welding Safety\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/\",\"url\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/\",\"name\":\"Welding to New Heights - Joe Welder\u2122 Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/wp-content\\\/new_ups\\\/default-featured-image.png\",\"datePublished\":\"2009-09-15T16:02:43+00:00\",\"description\":\"Welding to New Heights - Joe Welder\u2122 Blog -\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/2009\\\/09\\\/15\\\/welding-to-new-heights\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/wp-content\\\/new_ups\\\/default-featured-image.png\",\"contentUrl\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/wp-content\\\/new_ups\\\/default-featured-image.png\",\"width\":300,\"height\":200,\"caption\":\"Default Featured Image\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/#website\",\"url\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/\",\"name\":\"Joe Welder\u2122 Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/#organization\",\"name\":\"Arc-Zone.com, Inc.\",\"url\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/wp-content\\\/new_ups\\\/Circle-A-Logo2021_PANTONE.png\",\"contentUrl\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/wp-content\\\/new_ups\\\/Circle-A-Logo2021_PANTONE.png\",\"width\":1024,\"height\":977,\"caption\":\"Arc-Zone.com, Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ArcZone\",\"https:\\\/\\\/x.com\\\/arczone\",\"http:\\\/\\\/instagram.com\\\/arc_zone\",\"https:\\\/\\\/www.pinterest.com\\\/arczone\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/ArcZoneVideos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/#\\\/schema\\\/person\\\/d11eef7e30a3295231fc0ea473ff9505\",\"name\":\"Joe Welder\",\"sameAs\":[\"https:\\\/\\\/www.arc-zone.com\"],\"url\":\"https:\\\/\\\/blog.arc-zone.com\\\/joewelder\\\/author\\\/editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Welding to New Heights - Joe Welder\u2122 Blog","description":"Welding to New Heights - Joe Welder\u2122 Blog -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/","twitter_misc":{"Written by":"Joe Welder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/#article","isPartOf":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/"},"author":{"name":"Joe Welder","@id":"https:\/\/blog.arc-zone.com\/joewelder\/#\/schema\/person\/d11eef7e30a3295231fc0ea473ff9505"},"headline":"Welding to New Heights","datePublished":"2009-09-15T16:02:43+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/"},"wordCount":44,"commentCount":0,"publisher":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/#organization"},"image":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.arc-zone.com\/joewelder\/wp-content\/new_ups\/default-featured-image.png","articleSection":["History","Welding Kicks","Welding Safety"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/","url":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/","name":"Welding to New Heights - Joe Welder\u2122 Blog","isPartOf":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/#primaryimage"},"image":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.arc-zone.com\/joewelder\/wp-content\/new_ups\/default-featured-image.png","datePublished":"2009-09-15T16:02:43+00:00","description":"Welding to New Heights - Joe Welder\u2122 Blog -","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blog.arc-zone.com\/joewelder\/2009\/09\/15\/welding-to-new-heights\/#primaryimage","url":"https:\/\/blog.arc-zone.com\/joewelder\/wp-content\/new_ups\/default-featured-image.png","contentUrl":"https:\/\/blog.arc-zone.com\/joewelder\/wp-content\/new_ups\/default-featured-image.png","width":300,"height":200,"caption":"Default Featured Image"},{"@type":"WebSite","@id":"https:\/\/blog.arc-zone.com\/joewelder\/#website","url":"https:\/\/blog.arc-zone.com\/joewelder\/","name":"Joe Welder\u2122 Blog","description":"","publisher":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.arc-zone.com\/joewelder\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blog.arc-zone.com\/joewelder\/#organization","name":"Arc-Zone.com, Inc.","url":"https:\/\/blog.arc-zone.com\/joewelder\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blog.arc-zone.com\/joewelder\/#\/schema\/logo\/image\/","url":"https:\/\/blog.arc-zone.com\/joewelder\/wp-content\/new_ups\/Circle-A-Logo2021_PANTONE.png","contentUrl":"https:\/\/blog.arc-zone.com\/joewelder\/wp-content\/new_ups\/Circle-A-Logo2021_PANTONE.png","width":1024,"height":977,"caption":"Arc-Zone.com, Inc."},"image":{"@id":"https:\/\/blog.arc-zone.com\/joewelder\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ArcZone","https:\/\/x.com\/arczone","http:\/\/instagram.com\/arc_zone","https:\/\/www.pinterest.com\/arczone","http:\/\/www.youtube.com\/user\/ArcZoneVideos"]},{"@type":"Person","@id":"https:\/\/blog.arc-zone.com\/joewelder\/#\/schema\/person\/d11eef7e30a3295231fc0ea473ff9505","name":"Joe Welder","sameAs":["https:\/\/www.arc-zone.com"],"url":"https:\/\/blog.arc-zone.com\/joewelder\/author\/editor\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.arc-zone.com\/joewelder\/wp-json\/wp\/v2\/posts\/1737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.arc-zone.com\/joewelder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.arc-zone.com\/joewelder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.arc-zone.com\/joewelder\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.arc-zone.com\/joewelder\/wp-json\/wp\/v2\/comments?post=1737"}],"version-history":[{"count":11,"href":"https:\/\/blog.arc-zone.com\/joewelder\/wp-json\/wp\/v2\/posts\/1737\/revisions"}],"predecessor-version":[{"id":1753,"href":"https:\/\/blog.arc-zone.com\/joewelder\/wp-json\/wp\/v2\/posts\/1737\/revisions\/1753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.arc-zone.com\/joewelder\/wp-json\/wp\/v2\/media\/8560"}],"wp:attachment":[{"href":"https:\/\/blog.arc-zone.com\/joewelder\/wp-json\/wp\/v2\/media?parent=1737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.arc-zone.com\/joewelder\/wp-json\/wp\/v2\/categories?post=1737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.arc-zone.com\/joewelder\/wp-json\/wp\/v2\/tags?post=1737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}